{"id":2097,"count":19,"description":"","link":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/","name":"Attrezzatura per l'allenamento del Jiu Jitsu","slug":"attrezzatura-per-lallenamento-del-jiu-jitsu","taxonomy":"product_cat","parent":2359,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attrezzatura per l&#039;allenamento del Jiu Jitsu &#8211; Daisho<\/title>\n<meta name=\"description\" content=\"Scopri le attrezzature per l&#039;allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attrezzatura per l&#039;allenamento del Jiu Jitsu &#8211; Daisho\" \/>\n<meta property=\"og:description\" content=\"Scopri le attrezzature per l&#039;allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/\" \/>\n<meta property=\"og:site_name\" content=\"Daisho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/jujitsu-brasiliano-e-jiu-jitsu\\\/attrezzatura-per-lallenamento-del-jiu-jitsu\\\/\",\"url\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/jujitsu-brasiliano-e-jiu-jitsu\\\/attrezzatura-per-lallenamento-del-jiu-jitsu\\\/\",\"name\":\"Attrezzatura per l'allenamento del Jiu Jitsu &#8211; Daisho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#website\"},\"description\":\"Scopri le attrezzature per l'allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/jujitsu-brasiliano-e-jiu-jitsu\\\/attrezzatura-per-lallenamento-del-jiu-jitsu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/jujitsu-brasiliano-e-jiu-jitsu\\\/attrezzatura-per-lallenamento-del-jiu-jitsu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attrezzature e abbigliamento per arti marziali e sport da combattimento\",\"item\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jujitsu brasiliano e Jiu-Jitsu\",\"item\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/categorie-produit\\\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\\\/jujitsu-brasiliano-e-jiu-jitsu\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Attrezzatura per l'allenamento del Jiu Jitsu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/\",\"name\":\"Daisho\",\"description\":\"Sp&eacute;cialiste de l'&eacute;quipement sportif d'arts martiaux\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#organization\",\"name\":\"Daisho\",\"url\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.daisho.be\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/color-nothing-horizontale4x-e1564486100247.png\",\"contentUrl\":\"http:\\\/\\\/www.daisho.be\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/color-nothing-horizontale4x-e1564486100247.png\",\"width\":1547,\"height\":385,\"caption\":\"Daisho\"},\"image\":{\"@id\":\"https:\\\/\\\/www.daisho.be\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attrezzatura per l'allenamento del Jiu Jitsu &#8211; Daisho","description":"Scopri le attrezzature per l'allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/","og_locale":"it_IT","og_type":"article","og_title":"Attrezzatura per l'allenamento del Jiu Jitsu &#8211; Daisho","og_description":"Scopri le attrezzature per l'allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho","og_url":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/","og_site_name":"Daisho","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/","url":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/","name":"Attrezzatura per l'allenamento del Jiu Jitsu &#8211; Daisho","isPartOf":{"@id":"https:\/\/www.daisho.be\/it\/#website"},"description":"Scopri le attrezzature per l'allenamento appositamente studiate per migliorare le tue prestazioni e il tuo allenamento. Acquistalo su www.daisho.be|Daisho","breadcrumb":{"@id":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/attrezzatura-per-lallenamento-del-jiu-jitsu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.daisho.be\/it\/"},{"@type":"ListItem","position":2,"name":"Attrezzature e abbigliamento per arti marziali e sport da combattimento","item":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/"},{"@type":"ListItem","position":3,"name":"Jujitsu brasiliano e Jiu-Jitsu","item":"https:\/\/www.daisho.be\/it\/categorie-produit\/attrezzature-e-abbigliamento-per-arti-marziali-e-sport-da-combattimento\/jujitsu-brasiliano-e-jiu-jitsu\/"},{"@type":"ListItem","position":4,"name":"Attrezzatura per l'allenamento del Jiu Jitsu"}]},{"@type":"WebSite","@id":"https:\/\/www.daisho.be\/it\/#website","url":"https:\/\/www.daisho.be\/it\/","name":"Daisho","description":"Sp&eacute;cialiste de l'&eacute;quipement sportif d'arts martiaux","publisher":{"@id":"https:\/\/www.daisho.be\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.daisho.be\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.daisho.be\/it\/#organization","name":"Daisho","url":"https:\/\/www.daisho.be\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.daisho.be\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.daisho.be\/wp-content\/uploads\/2019\/07\/color-nothing-horizontale4x-e1564486100247.png","contentUrl":"https:\/\/www.daisho.be\/wp-content\/uploads\/2019\/07\/color-nothing-horizontale4x-e1564486100247.png","width":1547,"height":385,"caption":"Daisho"},"image":{"@id":"https:\/\/www.daisho.be\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.daisho.be\/it\/wp-json\/wp\/v2\/product_cat\/2097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.daisho.be\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.daisho.be\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.daisho.be\/it\/wp-json\/wp\/v2\/product_cat\/2359"}],"wp:post_type":[{"href":"https:\/\/www.daisho.be\/it\/wp-json\/wp\/v2\/product?product_cat=2097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}